{"id":4788,"count":11,"description":"<h1>Hefel Winter Duvet \u2013 Warmth That Doesn't Weigh You Down<\/h1>\r\nWarmth that doesn't weigh you down: Hefel winter duvets \u2014 warmth class 4\u20135 \u2014 keep you warm even on the coldest nights without lying heavy on the body. Down duvets trap air efficiently and feel weightless; virgin wool and cashmere provide outstanding insulation. All NOMITE certified. Overview: <a href=\"\/en\/linen-weaving-mills\/hefel\/\">Hefel<\/a>.","link":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/","name":"Hefel Winter Duvet","slug":"hefel-winter-duvet","taxonomy":"product_brand","parent":4782,"meta":{"b2bking_group_b2c":[],"b2bking_group_0":[],"b2bking_group_142309":[]},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hefel Winterdecke | W\u00e4rme, die nicht erdr\u00fcckt<\/title>\n<meta name=\"description\" content=\"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hefel Winter Duvet Archive\" \/>\n<meta property=\"og:description\" content=\"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/\" \/>\n<meta property=\"og:site_name\" content=\"Linen.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@linenlounge\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/linen-weaving-mills\\\/hefel\\\/hefel-winter-duvet\\\/\",\"url\":\"https:\\\/\\\/linen.eu\\\/en\\\/linen-weaving-mills\\\/hefel\\\/hefel-winter-duvet\\\/\",\"name\":\"Hefel Winterdecke | W\u00e4rme, die nicht erdr\u00fcckt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#website\"},\"description\":\"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/linen-weaving-mills\\\/hefel\\\/hefel-winter-duvet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/linen-weaving-mills\\\/hefel\\\/hefel-winter-duvet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/linen.eu\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HEFEL\",\"item\":\"https:\\\/\\\/linen.eu\\\/en\\\/linen-weaving-mills\\\/hefel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hefel Winter Duvet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/linen.eu\\\/en\\\/\",\"name\":\"Linen Lounge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linen.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#organization\",\"name\":\"Linen Lounge\",\"alternateName\":\"linen.eu\",\"url\":\"https:\\\/\\\/linen.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linen.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LinenLounge-NEU2.webp\",\"contentUrl\":\"https:\\\/\\\/linen.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LinenLounge-NEU2.webp\",\"width\":1800,\"height\":455,\"caption\":\"Linen Lounge\"},\"image\":{\"@id\":\"https:\\\/\\\/linen.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/linen.eu\",\"https:\\\/\\\/x.com\\\/linenlounge\",\"https:\\\/\\\/www.instagram.com\\\/linen.lounge?igsh=MW81aGhiY2VxZGRpMw==&utm_source=qr\",\"http:\\\/\\\/www.youtube.com\\\/@Linenlounge\"],\"description\":\"Online Fachhandel f\u00fcr europ\u00e4ische Leinen-Bettw\u00e4sche und Heimtextilien aus traditionellen Webereien wie Leitner Leinen, Schlitzer Leinen, Libeco, Vieb\u00f6ck und Hoffmann.\",\"email\":\"info@linen.eu\",\"telephone\":\"+49 (0) 69 90738860\",\"legalName\":\"Linen UG (haftungsbeschr\u00e4nkt)\",\"foundingDate\":\"2015-04-08\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hefel Winterdecke | W\u00e4rme, die nicht erdr\u00fcckt","description":"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/","og_locale":"en_US","og_type":"article","og_title":"Hefel Winter Duvet Archive","og_description":"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.","og_url":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/","og_site_name":"Linen.eu","twitter_card":"summary_large_image","twitter_site":"@linenlounge","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/","url":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/","name":"Hefel Winterdecke | W\u00e4rme, die nicht erdr\u00fcckt","isPartOf":{"@id":"https:\/\/linen.eu\/en\/#website"},"description":"Hefel Winterdecken aus \u00d6sterreich \u2014 w\u00e4rmend, ohne zu erdr\u00fccken. Daunen, Seide oder Schurwolle f\u00fcr tiefen Schlaf in kalten N\u00e4chten.","breadcrumb":{"@id":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/hefel-winter-duvet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/linen.eu\/en\/home\/"},{"@type":"ListItem","position":2,"name":"HEFEL","item":"https:\/\/linen.eu\/en\/linen-weaving-mills\/hefel\/"},{"@type":"ListItem","position":3,"name":"Hefel Winter Duvet"}]},{"@type":"WebSite","@id":"https:\/\/linen.eu\/en\/#website","url":"https:\/\/linen.eu\/en\/","name":"Linen Lounge","description":"","publisher":{"@id":"https:\/\/linen.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linen.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/linen.eu\/en\/#organization","name":"Linen Lounge","alternateName":"linen.eu","url":"https:\/\/linen.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/linen.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/linen.eu\/wp-content\/uploads\/2025\/10\/LinenLounge-NEU2.webp","contentUrl":"https:\/\/linen.eu\/wp-content\/uploads\/2025\/10\/LinenLounge-NEU2.webp","width":1800,"height":455,"caption":"Linen Lounge"},"image":{"@id":"https:\/\/linen.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/linen.eu","https:\/\/x.com\/linenlounge","https:\/\/www.instagram.com\/linen.lounge?igsh=MW81aGhiY2VxZGRpMw==&utm_source=qr","http:\/\/www.youtube.com\/@Linenlounge"],"description":"Online Fachhandel f\u00fcr europ\u00e4ische Leinen-Bettw\u00e4sche und Heimtextilien aus traditionellen Webereien wie Leitner Leinen, Schlitzer Leinen, Libeco, Vieb\u00f6ck und Hoffmann.","email":"info@linen.eu","telephone":"+49 (0) 69 90738860","legalName":"Linen UG (haftungsbeschr\u00e4nkt)","foundingDate":"2015-04-08","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/linen.eu\/en\/wp-json\/wp\/v2\/product_brand\/4788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linen.eu\/en\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/linen.eu\/en\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"up":[{"embeddable":true,"href":"https:\/\/linen.eu\/en\/wp-json\/wp\/v2\/product_brand\/4782"}],"wp:post_type":[{"href":"https:\/\/linen.eu\/en\/wp-json\/wp\/v2\/product?product_brand=4788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}